{"id":40208,"date":"2025-12-16T19:53:46","date_gmt":"2025-12-16T19:53:46","guid":{"rendered":"https:\/\/seekapa.com\/become-a-partner-form\/"},"modified":"2025-12-16T19:53:46","modified_gmt":"2025-12-16T19:53:46","slug":"become-a-partner-form","status":"publish","type":"page","link":"https:\/\/sktrd.org\/pt\/become-a-partner-form\/","title":{"rendered":"Become A Partner Form"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"40208\" class=\"elementor elementor-40208\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9203d23 e-flex e-con-boxed e-con e-parent\" data-id=\"9203d23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a5264c6 e-con-full e-flex e-con e-child\" data-id=\"a5264c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b53320b e-con-full e-flex e-con e-child\" data-id=\"b53320b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b363f1 elementor-widget elementor-widget-heading\" data-id=\"4b363f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span>Become A Seekapa Partner <\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7592ea7 elementor-widget elementor-widget-wpforms\" data-id=\"7592ea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-border-style: solid;\n--wpforms-field-border-size: 1px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-border-color-spare: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-field-menu-color: #ffffff;\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-border-style: none;\n--wpforms-button-border-size: 1px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-border-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-page-break-color: #066aab;\n--wpforms-background-image: none;\n--wpforms-background-position: center center;\n--wpforms-background-repeat: no-repeat;\n--wpforms-background-size: cover;\n--wpforms-background-width: 100px;\n--wpforms-background-height: 100px;\n--wpforms-background-color: rgba( 0, 0, 0, 0 );\n--wpforms-background-url: none;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-style: none;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-color: #000000;\n--wpforms-container-border-radius: 3px;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-7592ea7\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-7592ea7 {\n\t\t\t\t\t--wpforms-field-text-color: #000000B3;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full become-partner-form-wrap wpforms-render-modern\" id=\"wpforms-22144\"><form id=\"wpforms-form-22144\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"22144\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/40208\" data-token=\"3f3212007cd99cb7659af786858ba96c\" data-token-time=\"1784078032\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-22144-field_12-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"12\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_2\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-22144-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Enter your name\" aria-errormessage=\"wpforms-22144-field_2-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_3\">Company <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-22144-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Enter your company name\" aria-errormessage=\"wpforms-22144-field_3-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_4\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-22144-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"example@mail.com\" spellcheck=\"false\" aria-errormessage=\"wpforms-22144-field_4-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_15-container\" class=\"wpforms-field wpforms-field-url\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_15\">Domain<\/label><input type=\"url\" id=\"wpforms-22144-field_15\" class=\"wpforms-field-medium\" name=\"wpforms[fields][15]\" placeholder=\"example.com\" aria-errormessage=\"wpforms-22144-field_15-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_21-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_21\">Phone<\/label><input type=\"tel\" id=\"wpforms-22144-field_21\" class=\"wpforms-field-medium\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][21]\" placeholder=\"Enter your phone\" aria-errormessage=\"wpforms-22144-field_21-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_28-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_28\">Traffic Source Countries<\/label><input type=\"text\" id=\"wpforms-22144-field_28\" class=\"wpforms-field-medium\" name=\"wpforms[fields][28]\" placeholder=\"Example: United Arab, Qatar\" aria-errormessage=\"wpforms-22144-field_28-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_9\">Traffic Sources <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-22144-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"SEO\/Blogging\" >SEO\/Blogging<\/option><option value=\"Social Media\" >Social Media<\/option><option value=\"Youtube\" >Youtube<\/option><option value=\"Contextual\" >Contextual<\/option><option value=\"Email\" >Email<\/option><option value=\"Facebook\" >Facebook<\/option><option value=\"Instagram\" >Instagram<\/option><option value=\"Other\" >Other<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_10-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_10\">Skype <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-22144-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" placeholder=\"Enter your number\" aria-errormessage=\"wpforms-22144-field_10-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-22144-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-22144-field_11\">Telegram<\/label><input type=\"text\" id=\"wpforms-22144-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" placeholder=\"Enter your user\" aria-errormessage=\"wpforms-22144-field_11-error\" ><\/div><\/div><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"22144\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/pages\/40208\">\t\t<div id=\"cf-turnstile-wpf-2268433460\"\r\n\t\tclass=\"cf-turnstile\" \t\tdata-sitekey=\"0x4AAAAAABmLIA1KhIrQCOKJ\"\r\n\t\tdata-theme=\"light\"\r\n\t\tdata-language=\"auto\"\r\n\t\tdata-size=\"normal\"\r\n\t\tdata-retry=\"auto\" data-retry-interval=\"1000\"\r\n\t\tdata-refresh-expired=\"auto\"\r\n\t\tdata-action=\"wpforms-22144\"\r\n\t\t\t\tdata-appearance=\"always\"><\/div>\r\n\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-wpf-2268433460\"); e&&!e.innerHTML.trim()&&(turnstile.remove(\"#cf-turnstile-wpf-2268433460\"), turnstile.render(\"#cf-turnstile-wpf-2268433460\", {sitekey:\"0x4AAAAAABmLIA1KhIrQCOKJ\"})); }, 100); });<\/script>\r\n\t\t\t<br class=\"cf-turnstile-br cf-turnstile-br-wpf-2268433460\">\r\n\t\t\t\t<style>#cf-turnstile-wpf-2268433460 { margin-left: -15px; }<\/style>\r\n\t\t<button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-22144\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Become A Seekapa Partner Please enable JavaScript in your browser to complete this form.Please enable JavaScript in your browser to complete this form.LayoutName *Company *Email *DomainPhoneTraffic Source CountriesTraffic Sources *SEO\/BloggingSocial MediaYoutubeContextualEmailFacebookInstagramOtherSkype *Telegram Submit<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-40208","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/pages\/40208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/comments?post=40208"}],"version-history":[{"count":0,"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/pages\/40208\/revisions"}],"wp:attachment":[{"href":"https:\/\/sktrd.org\/pt\/wp-json\/wp\/v2\/media?parent=40208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}